{"id":15155,"date":"2022-12-20T12:04:26","date_gmt":"2022-12-20T11:04:26","guid":{"rendered":"http:\/\/lekarnici.cz\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/"},"modified":"2026-07-15T04:00:55","modified_gmt":"2026-07-15T02:00:55","slug":"na-namesti-nam-t-g-masaryka-164-ceska-lipa","status":"publish","type":"lekarna","link":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/","title":{"rendered":"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed"},"template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"kategorie-otazek-a-odpovedi":[],"class_list":["post-15155","lekarna","type-lekarna","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/\" \/>\n<meta property=\"og:site_name\" content=\"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T02:00:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/\",\"url\":\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/\",\"name\":\"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\",\"isPartOf\":{\"@id\":\"https:\/\/lekarnici.cz\/en\/#website\"},\"datePublished\":\"2022-12-20T11:04:26+00:00\",\"dateModified\":\"2026-07-15T02:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/lekarnici.cz\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00e9k\u00e1rny\",\"item\":\"https:\/\/lekarnici.cz\/en\/lekarna\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lekarnici.cz\/en\/#website\",\"url\":\"https:\/\/lekarnici.cz\/en\/\",\"name\":\"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\",\"description\":\"\u010cLnK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lekarnici.cz\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/","og_locale":"en_US","og_type":"article","og_title":"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","og_url":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/","og_site_name":"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","article_modified_time":"2026-07-15T02:00:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/","url":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/","name":"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","isPartOf":{"@id":"https:\/\/lekarnici.cz\/en\/#website"},"datePublished":"2022-12-20T11:04:26+00:00","dateModified":"2026-07-15T02:00:55+00:00","breadcrumb":{"@id":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lekarnici.cz\/en\/lekarna\/na-namesti-nam-t-g-masaryka-164-ceska-lipa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/lekarnici.cz\/en\/"},{"@type":"ListItem","position":2,"name":"L\u00e9k\u00e1rny","item":"https:\/\/lekarnici.cz\/en\/lekarna\/"},{"@type":"ListItem","position":3,"name":"L\u00e9k\u00e1rna Na n\u00e1m\u011bst\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/lekarnici.cz\/en\/#website","url":"https:\/\/lekarnici.cz\/en\/","name":"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","description":"\u010cLnK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lekarnici.cz\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/lekarna\/15155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/lekarna"}],"about":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/types\/lekarna"}],"wp:attachment":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/media?parent=15155"}],"wp:term":[{"taxonomy":"kategorie-otazek-a-odpovedi","embeddable":true,"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/kategorie-otazek-a-odpovedi?post=15155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}