{"id":84873,"date":"2024-06-13T02:07:57","date_gmt":"2024-06-13T00:07:57","guid":{"rendered":"https:\/\/lekarnici.cz\/lekarnici\/laviaha-lizaveta-mgr\/"},"modified":"2026-05-13T02:09:52","modified_gmt":"2026-05-13T00:09:52","slug":"laviaha-lizaveta-mgr","status":"publish","type":"lekarnici","link":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/","title":{"rendered":"Laviaha Lizaveta Mgr."},"template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"class_list":["post-84873","lekarnici","type-lekarnici","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/\" \/>\n<meta property=\"og:site_name\" content=\"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:09:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/\",\"url\":\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/\",\"name\":\"Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\",\"isPartOf\":{\"@id\":\"https:\/\/lekarnici.cz\/en\/#website\"},\"datePublished\":\"2024-06-13T00:07:57+00:00\",\"dateModified\":\"2026-05-13T00:09:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/lekarnici.cz\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laviaha Lizaveta Mgr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lekarnici.cz\/en\/#website\",\"url\":\"https:\/\/lekarnici.cz\/en\/\",\"name\":\"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora\",\"description\":\"\u010cLnK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lekarnici.cz\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/","og_locale":"en_US","og_type":"article","og_title":"Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","og_url":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/","og_site_name":"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","article_modified_time":"2026-05-13T00:09:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/","url":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/","name":"Laviaha Lizaveta Mgr. | \u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","isPartOf":{"@id":"https:\/\/lekarnici.cz\/en\/#website"},"datePublished":"2024-06-13T00:07:57+00:00","dateModified":"2026-05-13T00:09:52+00:00","breadcrumb":{"@id":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lekarnici.cz\/en\/lekarnici\/laviaha-lizaveta-mgr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/lekarnici.cz\/en\/"},{"@type":"ListItem","position":2,"name":"Laviaha Lizaveta Mgr."}]},{"@type":"WebSite","@id":"https:\/\/lekarnici.cz\/en\/#website","url":"https:\/\/lekarnici.cz\/en\/","name":"\u010cesk\u00e1 l\u00e9k\u00e1rnick\u00e1 komora","description":"\u010cLnK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lekarnici.cz\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/lekarnici\/84873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/lekarnici"}],"about":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/types\/lekarnici"}],"wp:attachment":[{"href":"https:\/\/lekarnici.cz\/en\/wp-json\/wp\/v2\/media?parent=84873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}